{"id":3862,"count":1,"description":"","link":"https:\/\/worlduniversitydirectory.com\/edu\/tag\/billion\/","name":"billion","slug":"billion","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/worlduniversitydirectory.com\/edu\/wp-json\/wp\/v2\/tags\/3862"}],"collection":[{"href":"https:\/\/worlduniversitydirectory.com\/edu\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/worlduniversitydirectory.com\/edu\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/worlduniversitydirectory.com\/edu\/wp-json\/wp\/v2\/posts?tags=3862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}